{"id":1685,"date":"2016-07-13T21:15:31","date_gmt":"2016-07-13T19:15:31","guid":{"rendered":"http:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508.jpg"},"modified":"2016-07-13T21:15:31","modified_gmt":"2016-07-13T19:15:31","slug":"20130729_170508","status":"inherit","type":"attachment","link":"https:\/\/dreamersjourneys.com\/de\/florence-bella-italia\/20130729_170508\/","title":{"rendered":"20130729_170508"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":""},"translation":{"provider":"WPGlobus","version":"2.12.2","language":"de","enabled_languages":["en","de"],"languages":{"en":{"title":true},"de":{"title":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>20130729_170508 - Dreamers Journeys<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508.jpg\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"20130729_170508 - Dreamers Journeys\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Dreamers Journeys\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"389\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508.jpg\",\"url\":\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508.jpg\",\"name\":\"20130729_170508 - Dreamers Journeys\",\"isPartOf\":{\"@id\":\"https:\/\/dreamersjourneys.com\/#website\"},\"datePublished\":\"2016-07-13T19:15:31+00:00\",\"dateModified\":\"2016-07-13T19:15:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508.jpg#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/dreamersjourneys.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Florence &#8211; Bella Italia\",\"item\":\"https:\/\/dreamersjourneys.com\/florence-bella-italia\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"20130729_170508\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dreamersjourneys.com\/#website\",\"url\":\"https:\/\/dreamersjourneys.com\/\",\"name\":\"Dreamers Journeys\",\"description\":\"Reise- und Erlebnisse\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dreamersjourneys.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"20130729_170508 - Dreamers Journeys","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508.jpg","og_locale":"de_DE","og_type":"article","og_title":"20130729_170508 - Dreamers Journeys","og_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508.jpg","og_site_name":"Dreamers Journeys","og_image":[{"width":1600,"height":389,"url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508.jpg","url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508.jpg","name":"20130729_170508 - Dreamers Journeys","isPartOf":{"@id":"https:\/\/dreamersjourneys.com\/#website"},"datePublished":"2016-07-13T19:15:31+00:00","dateModified":"2016-07-13T19:15:31+00:00","breadcrumb":{"@id":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508.jpg#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dreamersjourneys.com\/"},{"@type":"ListItem","position":2,"name":"Florence &#8211; Bella Italia","item":"https:\/\/dreamersjourneys.com\/florence-bella-italia\/"},{"@type":"ListItem","position":3,"name":"20130729_170508"}]},{"@type":"WebSite","@id":"https:\/\/dreamersjourneys.com\/#website","url":"https:\/\/dreamersjourneys.com\/","name":"Dreamers Journeys","description":"Reise- und Erlebnisse","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dreamersjourneys.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"73\" src=\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508-300x73.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508-300x73.jpg 300w, https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508-1024x249.jpg 1024w, https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508-604x147.jpg 604w, https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1600,"height":389,"file":"2013\/08\/20130729_170508.jpg","sizes":{"thumbnail":{"file":"20130729_170508-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508-150x150.jpg"},"medium":{"file":"20130729_170508-300x73.jpg","width":300,"height":73,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508-300x73.jpg"},"large":{"file":"20130729_170508-1024x249.jpg","width":1024,"height":249,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508-1024x249.jpg"},"post-thumbnail":{"file":"20130729_170508-604x147.jpg","width":604,"height":147,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508-604x147.jpg"},"nisarg-full-width":{"file":"20130729_170508-1038x389.jpg","width":1038,"height":389,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508-1038x389.jpg"},"full":{"file":"20130729_170508.jpg","width":1600,"height":389,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":1681,"source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2013\/08\/20130729_170508.jpg","_links":{"self":[{"href":"https:\/\/dreamersjourneys.com\/de\/wp-json\/wp\/v2\/media\/1685"}],"collection":[{"href":"https:\/\/dreamersjourneys.com\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/dreamersjourneys.com\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/dreamersjourneys.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dreamersjourneys.com\/de\/wp-json\/wp\/v2\/comments?post=1685"}]}}