{"id":2621,"date":"2019-01-25T21:08:09","date_gmt":"2019-01-25T19:08:09","guid":{"rendered":"http:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250.jpg"},"modified":"2019-01-25T21:21:42","modified_gmt":"2019-01-25T19:21:42","slug":"20190101_000250","status":"inherit","type":"attachment","link":"https:\/\/dreamersjourneys.com\/de\/20190101_000250\/","title":{"rendered":"20190101_000250"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":""},"translation":{"provider":"WPGlobus","version":"2.12.2","language":"de","enabled_languages":["en","de"],"languages":{"en":{"title":true},"de":{"title":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>20190101_000250 - Dreamers Journeys<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347.jpg\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"20190101_000250 - Dreamers Journeys\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Dreamers Journeys\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-25T19:21:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1960\" \/>\n\t<meta property=\"og:image:height\" content=\"4032\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347.jpg\",\"url\":\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347.jpg\",\"name\":\"20190101_000250 - Dreamers Journeys\",\"isPartOf\":{\"@id\":\"https:\/\/dreamersjourneys.com\/#website\"},\"datePublished\":\"2019-01-25T19:08:09+00:00\",\"dateModified\":\"2019-01-25T19:21:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347.jpg#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/dreamersjourneys.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"20190101_000250\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dreamersjourneys.com\/#website\",\"url\":\"https:\/\/dreamersjourneys.com\/\",\"name\":\"Dreamers Journeys\",\"description\":\"Reise- und Erlebnisse\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dreamersjourneys.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"20190101_000250 - Dreamers Journeys","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347.jpg","og_locale":"de_DE","og_type":"article","og_title":"20190101_000250 - Dreamers Journeys","og_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347.jpg","og_site_name":"Dreamers Journeys","article_modified_time":"2019-01-25T19:21:42+00:00","og_image":[{"width":1960,"height":4032,"url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347.jpg","url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347.jpg","name":"20190101_000250 - Dreamers Journeys","isPartOf":{"@id":"https:\/\/dreamersjourneys.com\/#website"},"datePublished":"2019-01-25T19:08:09+00:00","dateModified":"2019-01-25T19:21:42+00:00","breadcrumb":{"@id":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347.jpg#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dreamersjourneys.com\/"},{"@type":"ListItem","position":2,"name":"20190101_000250"}]},{"@type":"WebSite","@id":"https:\/\/dreamersjourneys.com\/#website","url":"https:\/\/dreamersjourneys.com\/","name":"Dreamers Journeys","description":"Reise- und Erlebnisse","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dreamersjourneys.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"146\" height=\"300\" src=\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347-146x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347-146x300.jpg 146w, https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347-498x1024.jpg 498w, https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347-131x270.jpg 131w, https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347.jpg 1960w\" sizes=\"(max-width: 146px) 100vw, 146px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1960,"height":4032,"file":"2019\/01\/20190101_000250-e1548444098347.jpg","sizes":{"thumbnail":{"file":"20190101_000250-e1548444098347-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347-150x150.jpg"},"medium":{"file":"20190101_000250-e1548444098347-146x300.jpg","width":146,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347-146x300.jpg"},"large":{"file":"20190101_000250-e1548444098347-498x1024.jpg","width":498,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347-498x1024.jpg"},"post-thumbnail":{"file":"20190101_000250-e1548444098347-131x270.jpg","width":131,"height":270,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347-131x270.jpg"},"nisarg-full-width":{"file":"20190101_000250-e1548444098347-1038x576.jpg","width":1038,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347-1038x576.jpg"},"full":{"file":"20190101_000250-e1548444098347.jpg","width":1960,"height":4032,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347.jpg"}},"image_meta":{"aperture":"1.5","credit":"","camera":"SM-G960F","caption":"","created_timestamp":"1546300970","copyright":"","focal_length":"4.3","iso":"1000","shutter_speed":"0.16666666666667","title":"","orientation":"6","keywords":[]}},"post":null,"source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/01\/20190101_000250-e1548444098347.jpg","_links":{"self":[{"href":"https:\/\/dreamersjourneys.com\/de\/wp-json\/wp\/v2\/media\/2621"}],"collection":[{"href":"https:\/\/dreamersjourneys.com\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/dreamersjourneys.com\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/dreamersjourneys.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dreamersjourneys.com\/de\/wp-json\/wp\/v2\/comments?post=2621"}]}}