{"id":2770,"date":"2019-05-16T19:35:03","date_gmt":"2019-05-16T17:35:03","guid":{"rendered":"http:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027.jpg"},"modified":"2019-05-16T19:43:39","modified_gmt":"2019-05-16T17:43:39","slug":"20190404_130027","status":"inherit","type":"attachment","link":"https:\/\/dreamersjourneys.com\/de\/20190404_130027\/","title":{"rendered":"20190404_130027"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":""},"translation":{"provider":"WPGlobus","version":"2.12.2","language":"de","enabled_languages":["en","de"],"languages":{"en":{"title":true},"de":{"title":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>20190404_130027 - Dreamers Journeys<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693.jpg\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"20190404_130027 - Dreamers Journeys\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Dreamers Journeys\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-16T17:43:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2448\" \/>\n\t<meta property=\"og:image:height\" content=\"3264\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693.jpg\",\"url\":\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693.jpg\",\"name\":\"20190404_130027 - Dreamers Journeys\",\"isPartOf\":{\"@id\":\"https:\/\/dreamersjourneys.com\/#website\"},\"datePublished\":\"2019-05-16T17:35:03+00:00\",\"dateModified\":\"2019-05-16T17:43:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693.jpg#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/dreamersjourneys.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"20190404_130027\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dreamersjourneys.com\/#website\",\"url\":\"https:\/\/dreamersjourneys.com\/\",\"name\":\"Dreamers Journeys\",\"description\":\"Reise- und Erlebnisse\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dreamersjourneys.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"20190404_130027 - Dreamers Journeys","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693.jpg","og_locale":"de_DE","og_type":"article","og_title":"20190404_130027 - Dreamers Journeys","og_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693.jpg","og_site_name":"Dreamers Journeys","article_modified_time":"2019-05-16T17:43:39+00:00","og_image":[{"width":2448,"height":3264,"url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693.jpg","url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693.jpg","name":"20190404_130027 - Dreamers Journeys","isPartOf":{"@id":"https:\/\/dreamersjourneys.com\/#website"},"datePublished":"2019-05-16T17:35:03+00:00","dateModified":"2019-05-16T17:43:39+00:00","breadcrumb":{"@id":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693.jpg#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dreamersjourneys.com\/"},{"@type":"ListItem","position":2,"name":"20190404_130027"}]},{"@type":"WebSite","@id":"https:\/\/dreamersjourneys.com\/#website","url":"https:\/\/dreamersjourneys.com\/","name":"Dreamers Journeys","description":"Reise- und Erlebnisse","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dreamersjourneys.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693-225x300.jpg 225w, https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693-768x1024.jpg 768w, https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693-203x270.jpg 203w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2448,"height":3264,"file":"2019\/05\/20190404_130027-e1558028615693.jpg","sizes":{"thumbnail":{"file":"20190404_130027-e1558028615693-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693-150x150.jpg"},"medium":{"file":"20190404_130027-e1558028615693-225x300.jpg","width":225,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693-225x300.jpg"},"large":{"file":"20190404_130027-e1558028615693-768x1024.jpg","width":768,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693-768x1024.jpg"},"post-thumbnail":{"file":"20190404_130027-e1558028615693-203x270.jpg","width":203,"height":270,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693-203x270.jpg"},"nisarg-full-width":{"file":"20190404_130027-e1558028615693-1038x576.jpg","width":1038,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693-1038x576.jpg"},"full":{"file":"20190404_130027-e1558028615693.jpg","width":2448,"height":3264,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693.jpg"}},"image_meta":{"aperture":"1.7","credit":"","camera":"SM-G960F","caption":"","created_timestamp":"1554382825","copyright":"","focal_length":"2.92","iso":"40","shutter_speed":"0.0024752475247525","title":"","orientation":"8","keywords":[]}},"post":null,"source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2019\/05\/20190404_130027-e1558028615693.jpg","_links":{"self":[{"href":"https:\/\/dreamersjourneys.com\/de\/wp-json\/wp\/v2\/media\/2770"}],"collection":[{"href":"https:\/\/dreamersjourneys.com\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/dreamersjourneys.com\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/dreamersjourneys.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dreamersjourneys.com\/de\/wp-json\/wp\/v2\/comments?post=2770"}]}}