{"id":351,"date":"2016-06-15T23:20:45","date_gmt":"2016-06-15T21:20:45","guid":{"rendered":"http:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937.jpg"},"modified":"2016-06-15T23:50:45","modified_gmt":"2016-06-15T21:50:45","slug":"dsc_6937","status":"inherit","type":"attachment","link":"https:\/\/dreamersjourneys.com\/de\/stonehenge-und-andere-schone-sehenswurdigkeiten\/dsc_6937\/","title":{"rendered":"DSC_6937"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":""},"translation":{"provider":"WPGlobus","version":"2.12.2","language":"de","enabled_languages":["en","de"],"languages":{"en":{"title":true},"de":{"title":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>DSC_6937 - Dreamers Journeys<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208.jpg\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DSC_6937 - Dreamers Journeys\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Dreamers Journeys\" \/>\n<meta property=\"article:modified_time\" content=\"2016-06-15T21:50:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2160\" \/>\n\t<meta property=\"og:image:height\" content=\"3840\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208.jpg\",\"url\":\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208.jpg\",\"name\":\"DSC_6937 - Dreamers Journeys\",\"isPartOf\":{\"@id\":\"https:\/\/dreamersjourneys.com\/#website\"},\"datePublished\":\"2016-06-15T21:20:45+00:00\",\"dateModified\":\"2016-06-15T21:50:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208.jpg#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/dreamersjourneys.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stonehenge und andere sch\u00f6ne Sehensw\u00fcrdigkeiten\",\"item\":\"https:\/\/dreamersjourneys.com\/de\/stonehenge-und-andere-schone-sehenswurdigkeiten\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DSC_6937\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dreamersjourneys.com\/#website\",\"url\":\"https:\/\/dreamersjourneys.com\/\",\"name\":\"Dreamers Journeys\",\"description\":\"Reise- und Erlebnisse\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dreamersjourneys.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DSC_6937 - Dreamers Journeys","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208.jpg","og_locale":"de_DE","og_type":"article","og_title":"DSC_6937 - Dreamers Journeys","og_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208.jpg","og_site_name":"Dreamers Journeys","article_modified_time":"2016-06-15T21:50:45+00:00","og_image":[{"width":2160,"height":3840,"url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208.jpg","url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208.jpg","name":"DSC_6937 - Dreamers Journeys","isPartOf":{"@id":"https:\/\/dreamersjourneys.com\/#website"},"datePublished":"2016-06-15T21:20:45+00:00","dateModified":"2016-06-15T21:50:45+00:00","breadcrumb":{"@id":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208.jpg#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dreamersjourneys.com\/"},{"@type":"ListItem","position":2,"name":"Stonehenge und andere sch\u00f6ne Sehensw\u00fcrdigkeiten","item":"https:\/\/dreamersjourneys.com\/de\/stonehenge-und-andere-schone-sehenswurdigkeiten\/"},{"@type":"ListItem","position":3,"name":"DSC_6937"}]},{"@type":"WebSite","@id":"https:\/\/dreamersjourneys.com\/#website","url":"https:\/\/dreamersjourneys.com\/","name":"Dreamers Journeys","description":"Reise- und Erlebnisse","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dreamersjourneys.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208-169x300.jpg 169w, https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208-576x1024.jpg 576w, https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208-152x270.jpg 152w\" sizes=\"(max-width: 169px) 100vw, 169px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2160,"height":3840,"file":"2016\/06\/DSC_6937-e1466025772208.jpg","sizes":{"thumbnail":{"file":"DSC_6937-e1466025772208-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208-150x150.jpg"},"medium":{"file":"DSC_6937-e1466025772208-169x300.jpg","width":169,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208-169x300.jpg"},"large":{"file":"DSC_6937-e1466025772208-576x1024.jpg","width":576,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208-576x1024.jpg"},"post-thumbnail":{"file":"DSC_6937-e1466025772208-152x270.jpg","width":152,"height":270,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208-152x270.jpg"},"nisarg-full-width":{"file":"DSC_6937-e1466025772208-1038x576.jpg","width":1038,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208-1038x576.jpg"},"full":{"file":"DSC_6937-e1466025772208.jpg","width":2160,"height":3840,"mime_type":"image\/jpeg","source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208.jpg"}},"image_meta":{"aperture":"2","credit":"","camera":"D5503","caption":"","created_timestamp":"1435939210","copyright":"","focal_length":"4.9","iso":"125","shutter_speed":"0.03125","title":"","orientation":"6","keywords":[]}},"post":332,"source_url":"https:\/\/dreamersjourneys.com\/wp-content\/uploads\/2016\/06\/DSC_6937-e1466025772208.jpg","_links":{"self":[{"href":"https:\/\/dreamersjourneys.com\/de\/wp-json\/wp\/v2\/media\/351"}],"collection":[{"href":"https:\/\/dreamersjourneys.com\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/dreamersjourneys.com\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/dreamersjourneys.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dreamersjourneys.com\/de\/wp-json\/wp\/v2\/comments?post=351"}]}}